{"id":3074,"date":"2023-10-30T10:30:44","date_gmt":"2023-10-30T13:30:44","guid":{"rendered":"https:\/\/sulsc.com\/?p=3074"},"modified":"2023-10-30T09:31:23","modified_gmt":"2023-10-30T12:31:23","slug":"pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao","status":"publish","type":"post","link":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/","title":{"rendered":"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o"},"content":{"rendered":"<p>O setor de fiscaliza\u00e7\u00e3o do Procon de Tubar\u00e3o realizou, na \u00faltima quinta-feira (26), uma pesquisa dos pre\u00e7os do g\u00e1s de cozinha (GLP). A a\u00e7\u00e3o foi realizada em oito estabelecimentos. Foram pesquisados valores \u00e0 vista, no cart\u00e3o e no dinheiro, levando-se em conta tamb\u00e9m se a compra seria retirada no estabelecimento ou entregue.<\/p>\n<p>O menor valor praticado \u00e0 vista para retirada na distribuidora foi de R$ 80,00 e o maior de R$ 115,00. O menor valor praticado no cr\u00e9dito para retirada na distribuidora foi de 85,00, j\u00e1 o maior foi de R$ 120,00.<\/p>\n<p>Para entregas em domic\u00edlio o menor valor praticado para entrega com o pagamento \u00e0 vista foi de R$ 93,00 e o maior valor foi de R$ 120,00. Por sua vez, o menor valor praticado no cr\u00e9dito foi de R$ 96,00 e o maior de R$ 125,00. <a href=\"https:\/\/tubarao.sc.gov.br\/uploads\/sites\/265\/2023\/10\/08-outubro.pdf\">A pesquisa completa pode ser acessada ao clicar aqui<\/a>.<\/p>\n<p>Em caso de d\u00favidas ou den\u00fancias, o consumidor pode encontrar em contato com o Procon de Tubar\u00e3o por\u00a0 meio do telefone (48) 3621-9818 ou pelo e-mail: procon@tubarao.sc.gov.br.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-1624\" src=\"http:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-1024x731.jpg\" alt=\"\" width=\"1024\" height=\"731\" srcset=\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-1024x731.jpg 1024w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-300x214.jpg 300w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-768x549.jpg 768w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-1536x1097.jpg 1536w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-1-2048x1463.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Fonte: Pref. Tubar\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O setor de fiscaliza\u00e7\u00e3o do Procon de Tubar\u00e3o realizou, na \u00faltima quinta-feira (26), uma pesquisa dos pre\u00e7os do g\u00e1s de cozinha (GLP). A a\u00e7\u00e3o foi realizada em oito estabelecimentos. Foram pesquisados valores \u00e0 vista, no cart\u00e3o e no dinheiro, levando-se em conta tamb\u00e9m se a compra seria retirada no estabelecimento ou entregue. O menor valor &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\"> <span class=\"screen-reader-text\">Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":1623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[11,1,21],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -\" \/>\n<meta property=\"og:description\" content=\"O setor de fiscaliza\u00e7\u00e3o do Procon de Tubar\u00e3o realizou, na \u00faltima quinta-feira (26), uma pesquisa dos pre\u00e7os do g\u00e1s de cozinha (GLP). A a\u00e7\u00e3o foi realizada em oito estabelecimentos. Foram pesquisados valores \u00e0 vista, no cart\u00e3o e no dinheiro, levando-se em conta tamb\u00e9m se a compra seria retirada no estabelecimento ou entregue. O menor valor &hellip; Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T13:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T12:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/PortalSulSC\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\",\"url\":\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\",\"name\":\"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -\",\"isPartOf\":{\"@id\":\"https:\/\/sulsc.com\/#website\"},\"datePublished\":\"2023-10-30T13:30:44+00:00\",\"dateModified\":\"2023-10-30T12:31:23+00:00\",\"author\":{\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sulsc.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sulsc.com\/#website\",\"url\":\"https:\/\/sulsc.com\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sulsc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\",\"name\":\"Reda\u00e7\u00e3o Sul SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0\",\"url\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"contentUrl\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"caption\":\"Reda\u00e7\u00e3o Sul SC\"},\"description\":\"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!\",\"sameAs\":[\"https:\/\/sulsc.com\/\",\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\",\"https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC\",\"https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw\"],\"url\":\"https:\/\/sulsc.com\/index.php\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/","og_locale":"en_US","og_type":"article","og_title":"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -","og_description":"O setor de fiscaliza\u00e7\u00e3o do Procon de Tubar\u00e3o realizou, na \u00faltima quinta-feira (26), uma pesquisa dos pre\u00e7os do g\u00e1s de cozinha (GLP). A a\u00e7\u00e3o foi realizada em oito estabelecimentos. Foram pesquisados valores \u00e0 vista, no cart\u00e3o e no dinheiro, levando-se em conta tamb\u00e9m se a compra seria retirada no estabelecimento ou entregue. O menor valor &hellip; Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o Read More &raquo;","og_url":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=61559278119680","article_published_time":"2023-10-30T13:30:44+00:00","article_modified_time":"2023-10-30T12:31:23+00:00","og_image":[{"width":2560,"height":1829,"url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/renderizacao-3d-do-cilindro-de-gas-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Sul SC","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/PortalSulSC","twitter_misc":{"Written by":"Reda\u00e7\u00e3o Sul SC","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/","url":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/","name":"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o -","isPartOf":{"@id":"https:\/\/sulsc.com\/#website"},"datePublished":"2023-10-30T13:30:44+00:00","dateModified":"2023-10-30T12:31:23+00:00","author":{"@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3"},"breadcrumb":{"@id":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sulsc.com\/index.php\/2023\/10\/30\/pesquisa-mostra-diferenca-de-mais-de-40-no-preco-do-gas-de-cozinha-em-tubarao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sulsc.com\/"},{"@type":"ListItem","position":2,"name":"Pesquisa mostra diferen\u00e7a de mais de 40% no pre\u00e7o do g\u00e1s de cozinha, em Tubar\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/sulsc.com\/#website","url":"https:\/\/sulsc.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sulsc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3","name":"Reda\u00e7\u00e3o Sul SC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0","url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","contentUrl":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","caption":"Reda\u00e7\u00e3o Sul SC"},"description":"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!","sameAs":["https:\/\/sulsc.com\/","https:\/\/www.facebook.com\/profile.php?id=61559278119680","https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br","https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC","https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw"],"url":"https:\/\/sulsc.com\/index.php\/author\/redacao\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3074"}],"collection":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/comments?post=3074"}],"version-history":[{"count":1,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3074\/revisions"}],"predecessor-version":[{"id":3075,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3074\/revisions\/3075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media\/1623"}],"wp:attachment":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media?parent=3074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/categories?post=3074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/tags?post=3074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}