{"id":33212,"date":"2026-03-24T08:05:56","date_gmt":"2026-03-24T11:05:56","guid":{"rendered":"https:\/\/sulsc.com\/?p=33212"},"modified":"2026-03-24T08:05:56","modified_gmt":"2026-03-24T11:05:56","slug":"tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas","status":"publish","type":"post","link":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/","title":{"rendered":"Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas"},"content":{"rendered":"<p>A Prefeitura de Tubar\u00e3o, por meio da Funda\u00e7\u00e3o Municipal de Educa\u00e7\u00e3o, lan\u00e7ou o Edital n\u00ba 03\/2026, que rege o Processo Seletivo P\u00fablico Simplificado destinado \u00e0 sele\u00e7\u00e3o e contrata\u00e7\u00e3o de Professor de L\u00edngua Inglesa, Professor de Libras, Educador Social e Profissional de Apoio Escolar da Educa\u00e7\u00e3o B\u00e1sica, a serem admitidos, em car\u00e1ter tempor\u00e1rio, para o ano letivo de 2026.<\/p>\n<div id=\"metaslider-id-25573\" style=\"width: 100%;\" class=\"ml-slider-3-99-0 metaslider metaslider-flex metaslider-25573 ml-slider has-onhover-arrows ms-theme-default-base has-dots-nav\" role=\"region\" aria-label=\"Meio\" data-width=\"1200\">\n    <div id=\"metaslider_container_25573\">\n        <div id=\"metaslider_25573\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-25684 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-07-24 07:55:40\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2025\/07\/Marr-2-1000x166.jpg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-25684 msDefaultImage\" title=\"Marr 2\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-32412 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-02-18 13:59:46\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/02\/40dc1580-cad5-4867-bc58-c4243821ad38-1000x166.jpeg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-32412 msDefaultImage\" title=\"40dc1580-cad5-4867-bc58-c4243821ad38\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-32766 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-03-03 17:22:59\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/271ce739-f268-41c5-8051-3de1a1750359-1000x166.jpeg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-32766 msDefaultImage\" title=\"271ce739-f268-41c5-8051-3de1a1750359\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-33757 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-07 07:55:38\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/05\/156-anos-Banner-Aniversario-TB-1000x166.jpg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-33757 msDefaultImage\" title=\"156 anos - Banner Aniversario TB\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n<p>Ressalta-se que n\u00e3o podem participar deste processo os candidatos que tenham se classificado no Edital 22\/2025 nestas mesmas \u00e1reas de atua\u00e7\u00e3o.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser feitas exclusivamente de maneira online, <strong>come\u00e7ou as 19 horas desta segunda-feira (23) e se estender\u00e1 at\u00e9 as 13 horas desta quinta-feira (26)<\/strong>. Este processo \u00e9 composto de prova objetiva, prevista para acontecer no dia 30 de mar\u00e7o, e de prova de t\u00edtulos, cujos documentos devem ser entregues, presencialmente, na sede da funda\u00e7\u00e3o, localizada na Avenida Marcolino Martins Cabral, 336, Centro, entre os <strong>dias 24 e 26 de mar\u00e7o, das 13h15 \u00e0s 18h30.<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-33213\" src=\"http:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1.jpg\" alt=\"\" width=\"800\" height=\"445\" srcset=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1.jpg 800w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1-300x167.jpg 300w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1-768x427.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><strong>Todas as demais informa\u00e7\u00f5es, prazos, cronograma e regras do processo seletivo encontram-se dispon\u00edveis aqui:<\/strong> <strong><a class=\"edital-list-item-file\" href=\"https:\/\/tubarao.sc.gov.br\/uploads\/sites\/265\/2026\/03\/EDITAL-003_2026-1.pdf\">[23\/03\/2026] Edital 03\/2026 &#8211; Processo Seletivo &#8211; Educa\u00e7\u00e3o &#8211; Professores e Profissionais Educa\u00e7\u00e3o B\u00e1sica<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Tubar\u00e3o, por meio da Funda\u00e7\u00e3o Municipal de Educa\u00e7\u00e3o, lan\u00e7ou o Edital n\u00ba 03\/2026, que rege o Processo Seletivo P\u00fablico Simplificado destinado \u00e0 sele\u00e7\u00e3o e contrata\u00e7\u00e3o de Professor de L\u00edngua Inglesa, Professor de Libras, Educador Social e Profissional de Apoio Escolar da Educa\u00e7\u00e3o B\u00e1sica, a serem admitidos, em car\u00e1ter tempor\u00e1rio, para o ano &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\"> <span class=\"screen-reader-text\">Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":33213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[2231,2321,1,14,21,12],"tags":[1193],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Tubar\u00e3o, por meio da Funda\u00e7\u00e3o Municipal de Educa\u00e7\u00e3o, lan\u00e7ou o Edital n\u00ba 03\/2026, que rege o Processo Seletivo P\u00fablico Simplificado destinado \u00e0 sele\u00e7\u00e3o e contrata\u00e7\u00e3o de Professor de L\u00edngua Inglesa, Professor de Libras, Educador Social e Profissional de Apoio Escolar da Educa\u00e7\u00e3o B\u00e1sica, a serem admitidos, em car\u00e1ter tempor\u00e1rio, para o ano &hellip; Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T11:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/PortalSulSC\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\",\"url\":\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\",\"name\":\"Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -\",\"isPartOf\":{\"@id\":\"https:\/\/sulsc.com\/#website\"},\"datePublished\":\"2026-03-24T11:05:56+00:00\",\"dateModified\":\"2026-03-24T11:05:56+00:00\",\"author\":{\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sulsc.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sulsc.com\/#website\",\"url\":\"https:\/\/sulsc.com\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sulsc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\",\"name\":\"Reda\u00e7\u00e3o Sul SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0\",\"url\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"contentUrl\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"caption\":\"Reda\u00e7\u00e3o Sul SC\"},\"description\":\"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!\",\"sameAs\":[\"https:\/\/sulsc.com\/\",\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\",\"https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC\",\"https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw\"],\"url\":\"https:\/\/sulsc.com\/index.php\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/","og_locale":"en_US","og_type":"article","og_title":"Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -","og_description":"A Prefeitura de Tubar\u00e3o, por meio da Funda\u00e7\u00e3o Municipal de Educa\u00e7\u00e3o, lan\u00e7ou o Edital n\u00ba 03\/2026, que rege o Processo Seletivo P\u00fablico Simplificado destinado \u00e0 sele\u00e7\u00e3o e contrata\u00e7\u00e3o de Professor de L\u00edngua Inglesa, Professor de Libras, Educador Social e Profissional de Apoio Escolar da Educa\u00e7\u00e3o B\u00e1sica, a serem admitidos, em car\u00e1ter tempor\u00e1rio, para o ano &hellip; Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas Read More &raquo;","og_url":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=61559278119680","article_published_time":"2026-03-24T11:05:56+00:00","og_image":[{"width":800,"height":445,"url":"http:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/closeup-person-filling-out-questionary-form-1-800x445-1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Sul SC","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/PortalSulSC","twitter_misc":{"Written by":"Reda\u00e7\u00e3o Sul SC","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/","url":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/","name":"Tubar\u00e3o - Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas -","isPartOf":{"@id":"https:\/\/sulsc.com\/#website"},"datePublished":"2026-03-24T11:05:56+00:00","dateModified":"2026-03-24T11:05:56+00:00","author":{"@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3"},"breadcrumb":{"@id":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sulsc.com\/index.php\/2026\/03\/24\/tubarao-educacao-lanca-edital-para-professores-e-profissionais-em-diversas-areas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sulsc.com\/"},{"@type":"ListItem","position":2,"name":"Tubar\u00e3o &#8211; Educa\u00e7\u00e3o lan\u00e7a edital para professores e profissionais em diversas \u00e1reas"}]},{"@type":"WebSite","@id":"https:\/\/sulsc.com\/#website","url":"https:\/\/sulsc.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sulsc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3","name":"Reda\u00e7\u00e3o Sul SC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0","url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","contentUrl":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","caption":"Reda\u00e7\u00e3o Sul SC"},"description":"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!","sameAs":["https:\/\/sulsc.com\/","https:\/\/www.facebook.com\/profile.php?id=61559278119680","https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br","https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC","https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw"],"url":"https:\/\/sulsc.com\/index.php\/author\/redacao\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/33212"}],"collection":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/comments?post=33212"}],"version-history":[{"count":1,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/33212\/revisions"}],"predecessor-version":[{"id":33214,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/33212\/revisions\/33214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media\/33213"}],"wp:attachment":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media?parent=33212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/categories?post=33212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/tags?post=33212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}