{"id":3335,"date":"2023-11-03T16:00:57","date_gmt":"2023-11-03T19:00:57","guid":{"rendered":"https:\/\/sulsc.com\/?p=3335"},"modified":"2023-11-03T12:24:26","modified_gmt":"2023-11-03T15:24:26","slug":"eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo","status":"publish","type":"post","link":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/","title":{"rendered":"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo"},"content":{"rendered":"<p>Eletricistas da Celesc embarcam neste final de semana para o 8\u00ba Rodeio Nacional da categoria. A competi\u00e7\u00e3o, que ter\u00e1 R$ 46,8 mil em pr\u00eamios, vai eleger as principais equipes que executam tarefas no menor tempo, com boas pr\u00e1ticas e t\u00e9cnicas inovadoras. Nesta quarta-feira (1), os competidores se reuniram para intensificar os treinamentos.<\/p>\n<p>O torneio ser\u00e1 realizado durante o 24\u00ba Semin\u00e1rio Nacional de Distribui\u00e7\u00e3o de Energia El\u00e9trica (Sendi), considerado o maior evento de distribui\u00e7\u00e3o de energia el\u00e9trica da Am\u00e9rica Latina, que ocorre entre os dias 7 e 10 de novembro, no Esp\u00edrito Santo. Ao todo, dez profissionais da Celesc v\u00e3o participar do torneio.<\/p>\n<p>Eles foram selecionados dentre 50 candidatos por meio de seletivas internas, realizadas entre 8 e 19 de maio. Para a competi\u00e7\u00e3o, ser\u00e3o organizadas duas equipes com os selecionados (Celesc D1 e Celesc D2). Cada uma ser\u00e1 composta por um padrinho, dois ju\u00edzes, quatro eletricistas titulares e um reserva.<\/p>\n<p>\u201cO Rodeio Nacional de Eletricistas \u00e9 mais do que uma competi\u00e7\u00e3o. \u00c9 uma celebra\u00e7\u00e3o das melhores pr\u00e1ticas e da seguran\u00e7a no setor el\u00e9trico. Nossa participa\u00e7\u00e3o refor\u00e7a a mensagem de que a seguran\u00e7a \u00e9 uma parte essencial de nosso trabalho di\u00e1rio. Ao competir n\u00e3o apenas honramos o passado vitorioso da Celesc, mas tamb\u00e9m reafirmamos nosso compromisso de liderar pelo exemplo, garantindo que nossos eletricistas e t\u00e9cnicos realizem suas tarefas com a m\u00e1xima seguran\u00e7a em mente, todos os dias\u201d, destacou o presidente Tarc\u00edsio Rosa.<\/p>\n<p>Na mesma linha, a diretora de Gest\u00e3o Corporativa, Pilar Sabino da Silva, ressalta que o Rodeio \u00e9, antes de tudo, um evento sobre o trabalho seguro. &#8220;Ao treinar e desenvolver repetidamente procedimentos operacionais do cotidiano, o eletricista tem a oportunidade de aprimorar suas compet\u00eancias, pois desenvolve uma vis\u00e3o mais ampla e clara da sua forma de trabalhar. A seguran\u00e7a sempre foi uma bandeira priorit\u00e1ria na Empresa, e que est\u00e1 se fortalecendo cada vez mais. Vamos aproveitar essa oportunidade para disseminar pr\u00e1ticas de seguran\u00e7a de trabalho na nossa rede\u201d, refor\u00e7ou<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-3336\" src=\"http:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36-1024x507.jpeg\" alt=\"\" width=\"1024\" height=\"507\" srcset=\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36-1024x507.jpeg 1024w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36-300x149.jpeg 300w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36-768x380.jpeg 768w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36-1536x760.jpeg 1536w, https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Durante a competi\u00e7\u00e3o deste ano, ser\u00e3o avaliadas seis tarefas: substitui\u00e7\u00e3o de medidor; desenergiza\u00e7\u00e3o de circuito; substitui\u00e7\u00e3o das chaves fus\u00edveis; energiza\u00e7\u00e3o de circuito; escalada em poste circular utilizando degraus port\u00e1teis de fibra; eletricista com os olhos vendados que deve se aparelhar com os equipamentos de prote\u00e7\u00e3o individuais (EPIs); al\u00e9m da avalia\u00e7\u00e3o das melhores pr\u00e1ticas durante o torneio.<\/p>\n<p>\u201cEstamos treinando h\u00e1 meses e estamos otimistas. S\u00f3 de representar a Celesc em uma competi\u00e7\u00e3o nacional dessas j\u00e1 \u00e9 um grande orgulho. A cada dia, trabalhamos incansavelmente para garantir que nossos eletricistas e t\u00e9cnicos realizem suas tarefas com seguran\u00e7a em mente. Esta competi\u00e7\u00e3o \u00e9 uma oportunidade de mostrar ao mundo que a seguran\u00e7a \u00e9 a ess\u00eancia de nosso trabalho, e estamos orgulhosos de ser parte disso\u201d, ressaltou o engenheiro de Seguran\u00e7a do Trabalho, Eduardo Soldateli, que \u00e9 um dos coordenadores das equipes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eletricistas da Celesc embarcam neste final de semana para o 8\u00ba Rodeio Nacional da categoria. A competi\u00e7\u00e3o, que ter\u00e1 R$ 46,8 mil em pr\u00eamios, vai eleger as principais equipes que executam tarefas no menor tempo, com boas pr\u00e1ticas e t\u00e9cnicas inovadoras. Nesta quarta-feira (1), os competidores se reuniram para intensificar os treinamentos. O torneio ser\u00e1 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\"> <span class=\"screen-reader-text\">Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":3336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -\" \/>\n<meta property=\"og:description\" content=\"Eletricistas da Celesc embarcam neste final de semana para o 8\u00ba Rodeio Nacional da categoria. A competi\u00e7\u00e3o, que ter\u00e1 R$ 46,8 mil em pr\u00eamios, vai eleger as principais equipes que executam tarefas no menor tempo, com boas pr\u00e1ticas e t\u00e9cnicas inovadoras. Nesta quarta-feira (1), os competidores se reuniram para intensificar os treinamentos. O torneio ser\u00e1 &hellip; Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-03T19:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T15:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/PortalSulSC\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\",\"url\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\",\"name\":\"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -\",\"isPartOf\":{\"@id\":\"https:\/\/sulsc.com\/#website\"},\"datePublished\":\"2023-11-03T19:00:57+00:00\",\"dateModified\":\"2023-11-03T15:24:26+00:00\",\"author\":{\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sulsc.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sulsc.com\/#website\",\"url\":\"https:\/\/sulsc.com\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sulsc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\",\"name\":\"Reda\u00e7\u00e3o Sul SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0\",\"url\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"contentUrl\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"caption\":\"Reda\u00e7\u00e3o Sul SC\"},\"description\":\"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!\",\"sameAs\":[\"https:\/\/sulsc.com\/\",\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\",\"https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC\",\"https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw\"],\"url\":\"https:\/\/sulsc.com\/index.php\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/","og_locale":"en_US","og_type":"article","og_title":"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -","og_description":"Eletricistas da Celesc embarcam neste final de semana para o 8\u00ba Rodeio Nacional da categoria. A competi\u00e7\u00e3o, que ter\u00e1 R$ 46,8 mil em pr\u00eamios, vai eleger as principais equipes que executam tarefas no menor tempo, com boas pr\u00e1ticas e t\u00e9cnicas inovadoras. Nesta quarta-feira (1), os competidores se reuniram para intensificar os treinamentos. O torneio ser\u00e1 &hellip; Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo Read More &raquo;","og_url":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=61559278119680","article_published_time":"2023-11-03T19:00:57+00:00","article_modified_time":"2023-11-03T15:24:26+00:00","og_image":[{"width":1600,"height":792,"url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-03-at-09.53.36.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Sul SC","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/PortalSulSC","twitter_misc":{"Written by":"Reda\u00e7\u00e3o Sul SC","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/","url":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/","name":"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo -","isPartOf":{"@id":"https:\/\/sulsc.com\/#website"},"datePublished":"2023-11-03T19:00:57+00:00","dateModified":"2023-11-03T15:24:26+00:00","author":{"@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3"},"breadcrumb":{"@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/03\/eletricistas-da-celesc-embarcam-para-competicao-nacional-no-espirito-santo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sulsc.com\/"},{"@type":"ListItem","position":2,"name":"Eletricistas da Celesc embarcam para competi\u00e7\u00e3o nacional no Esp\u00edrito Santo"}]},{"@type":"WebSite","@id":"https:\/\/sulsc.com\/#website","url":"https:\/\/sulsc.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sulsc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3","name":"Reda\u00e7\u00e3o Sul SC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0","url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","contentUrl":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","caption":"Reda\u00e7\u00e3o Sul SC"},"description":"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!","sameAs":["https:\/\/sulsc.com\/","https:\/\/www.facebook.com\/profile.php?id=61559278119680","https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br","https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC","https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw"],"url":"https:\/\/sulsc.com\/index.php\/author\/redacao\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3335"}],"collection":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/comments?post=3335"}],"version-history":[{"count":1,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3335\/revisions"}],"predecessor-version":[{"id":3337,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3335\/revisions\/3337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media\/3336"}],"wp:attachment":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media?parent=3335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/categories?post=3335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/tags?post=3335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}