{"id":34633,"date":"2026-07-15T08:22:27","date_gmt":"2026-07-15T11:22:27","guid":{"rendered":"https:\/\/sulsc.com\/?p=34633"},"modified":"2026-07-15T08:22:27","modified_gmt":"2026-07-15T11:22:27","slug":"dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira","status":"publish","type":"post","link":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/","title":{"rendered":"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira"},"content":{"rendered":"<p>Quarta-feira (15), dia ensolarado e c\u00e9u limpo em boa parte de SC, j\u00e1 no Litoral sobretudo da Grande Florian\u00f3polis ao norte do estado, o sol aparece em meio a varia\u00e7\u00e3o de nuvens, devido ao vento de nordeste, que desloca umidade do mar. Ainda assim, n\u00e3o h\u00e1 indicativos de chuva.<\/p>\n<div id=\"metaslider-id-25573\" style=\"width: 100%;\" class=\"ml-slider-3-99-0 metaslider metaslider-flex metaslider-25573 ml-slider has-onhover-arrows ms-theme-default-base has-dots-nav\" role=\"region\" aria-label=\"Meio\" data-width=\"1200\">\n    <div id=\"metaslider_container_25573\">\n        <div id=\"metaslider_25573\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-25684 ms-image \" aria-roledescription=\"slide\" data-date=\"2025-07-24 07:55:40\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2025\/07\/Marr-2-1000x166.jpg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-25684 msDefaultImage\" title=\"Marr 2\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-32412 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-02-18 13:59:46\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/02\/40dc1580-cad5-4867-bc58-c4243821ad38-1000x166.jpeg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-32412 msDefaultImage\" title=\"40dc1580-cad5-4867-bc58-c4243821ad38\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-32766 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-03-03 17:22:59\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/03\/271ce739-f268-41c5-8051-3de1a1750359-1000x166.jpeg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-32766 msDefaultImage\" title=\"271ce739-f268-41c5-8051-3de1a1750359\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-34438 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-06-21 10:36:12\"><img src=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Banner_1000_185.jpg-1000x166.jpeg\" height=\"200\" width=\"1200\" alt=\"\" class=\"slider-25573 slide-34438 msDefaultImage\" title=\"Banner_1000_185.jpg\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n<p><strong>Temperaturas<\/strong><\/p>\n<p>O frio perde for\u00e7a, mas no amanhecer ainda ocorrem temperaturas pr\u00f3ximas a 0\u00b0C nas \u00e1reas altas dos planaltos, variam entre 8 e 15\u00b0C no Litoral e de 5\u00b0C a 13\u00b0C nas demais regi\u00f5es. \u00c0 tarde, as m\u00e1ximas ultrapassam os 20\u00b0C no Litoral e no oeste e variam de 15\u00b0C e 19\u00b0C nas demais regi\u00f5es.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-34635\" src=\"http:\/\/sulsc.com\/wp-content\/uploads\/2026\/07\/image-230.png\" alt=\"\" width=\"1068\" height=\"731\" srcset=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/07\/image-230.png 1068w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/07\/image-230-300x205.png 300w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/07\/image-230-1024x701.png 1024w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/07\/image-230-768x526.png 768w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-34340\" src=\"http:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Captura-de-tela-2026-03-07-023821-3.png\" alt=\"\" width=\"1317\" height=\"282\" srcset=\"https:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Captura-de-tela-2026-03-07-023821-3.png 1317w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Captura-de-tela-2026-03-07-023821-3-300x64.png 300w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Captura-de-tela-2026-03-07-023821-3-1024x219.png 1024w, https:\/\/sulsc.com\/wp-content\/uploads\/2026\/06\/Captura-de-tela-2026-03-07-023821-3-768x164.png 768w\" sizes=\"(max-width: 1317px) 100vw, 1317px\" \/><\/p>\n<p><strong>Vento:<\/strong>\u00a0 nordeste predomina e se intensifica no mar, pr\u00f3ximo \u00e0 costa do Litoral Sul, com rajadas ficando entre 50 e 70 km\/h, deixando o mar agitado, com ondas de leste a nordeste entre 2,0 e 2,5m. O risco \u00e9 baixo a moderado para ocorr\u00eancias associadas \u00e0 agita\u00e7\u00e3o mar\u00edtima.<\/p>\n<p><strong>Sistema predominante:<\/strong> alta press\u00e3o no oceano, favorecendo a circula\u00e7\u00e3o mar\u00edtima em SC.<\/p>\n<p><strong>Amanh\u00e3 quinta-feira (16),<\/strong> o tempo ser\u00e1 est\u00e1vel com sol e varia\u00e7\u00e3o de nuvens em no estado. Persiste a condi\u00e7\u00e3o de nevoeiros isolados ao amanhecer. O destaque ser\u00e1 nas temperaturas, com frio ao amanhecer e mais quente durante o dia, com m\u00e1ximas de 22\u00b0C a 28\u00b0C. O vento continua nordeste, com intensidade de fraco a moderado, com rajadas, mais intensas do Extremo Oeste ao Litoral Sul (50 a 70km\/h).<\/p>\n<p>Fontes: Defesa Civil-SC\/Epagri-Ciram<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quarta-feira (15), dia ensolarado e c\u00e9u limpo em boa parte de SC, j\u00e1 no Litoral sobretudo da Grande Florian\u00f3polis ao norte do estado, o sol aparece em meio a varia\u00e7\u00e3o de nuvens, devido ao vento de nordeste, que desloca umidade do mar. Ainda assim, n\u00e3o h\u00e1 indicativos de chuva. Temperaturas O frio perde for\u00e7a, mas &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\"> <span class=\"screen-reader-text\">Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":12676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[2354,2231,1,14,38,12],"tags":[90],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -\" \/>\n<meta property=\"og:description\" content=\"Quarta-feira (15), dia ensolarado e c\u00e9u limpo em boa parte de SC, j\u00e1 no Litoral sobretudo da Grande Florian\u00f3polis ao norte do estado, o sol aparece em meio a varia\u00e7\u00e3o de nuvens, devido ao vento de nordeste, que desloca umidade do mar. Ainda assim, n\u00e3o h\u00e1 indicativos de chuva. Temperaturas O frio perde for\u00e7a, mas &hellip; Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T11:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sulsc.com\/wp-content\/uploads\/2024\/05\/tempo-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/PortalSulSC\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\",\"url\":\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\",\"name\":\"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -\",\"isPartOf\":{\"@id\":\"https:\/\/sulsc.com\/#website\"},\"datePublished\":\"2026-07-15T11:22:27+00:00\",\"dateModified\":\"2026-07-15T11:22:27+00:00\",\"author\":{\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sulsc.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sulsc.com\/#website\",\"url\":\"https:\/\/sulsc.com\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sulsc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\",\"name\":\"Reda\u00e7\u00e3o Sul SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0\",\"url\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"contentUrl\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"caption\":\"Reda\u00e7\u00e3o Sul SC\"},\"description\":\"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!\",\"sameAs\":[\"https:\/\/sulsc.com\/\",\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\",\"https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC\",\"https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw\"],\"url\":\"https:\/\/sulsc.com\/index.php\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/","og_locale":"en_US","og_type":"article","og_title":"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -","og_description":"Quarta-feira (15), dia ensolarado e c\u00e9u limpo em boa parte de SC, j\u00e1 no Litoral sobretudo da Grande Florian\u00f3polis ao norte do estado, o sol aparece em meio a varia\u00e7\u00e3o de nuvens, devido ao vento de nordeste, que desloca umidade do mar. Ainda assim, n\u00e3o h\u00e1 indicativos de chuva. Temperaturas O frio perde for\u00e7a, mas &hellip; Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira Read More &raquo;","og_url":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=61559278119680","article_published_time":"2026-07-15T11:22:27+00:00","og_image":[{"width":1080,"height":603,"url":"http:\/\/sulsc.com\/wp-content\/uploads\/2024\/05\/tempo-1.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Sul SC","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/PortalSulSC","twitter_misc":{"Written by":"Reda\u00e7\u00e3o Sul SC","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/","url":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/","name":"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira -","isPartOf":{"@id":"https:\/\/sulsc.com\/#website"},"datePublished":"2026-07-15T11:22:27+00:00","dateModified":"2026-07-15T11:22:27+00:00","author":{"@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3"},"breadcrumb":{"@id":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sulsc.com\/index.php\/2026\/07\/15\/dia-ensolarado-e-maximas-passando-dos-18c-nesta-quarta-feira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sulsc.com\/"},{"@type":"ListItem","position":2,"name":"Dia ensolarado e m\u00e1ximas passando dos 18\u00b0C nesta quarta-feira"}]},{"@type":"WebSite","@id":"https:\/\/sulsc.com\/#website","url":"https:\/\/sulsc.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sulsc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3","name":"Reda\u00e7\u00e3o Sul SC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0","url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","contentUrl":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","caption":"Reda\u00e7\u00e3o Sul SC"},"description":"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!","sameAs":["https:\/\/sulsc.com\/","https:\/\/www.facebook.com\/profile.php?id=61559278119680","https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br","https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC","https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw"],"url":"https:\/\/sulsc.com\/index.php\/author\/redacao\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/34633"}],"collection":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/comments?post=34633"}],"version-history":[{"count":1,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/34633\/revisions"}],"predecessor-version":[{"id":34636,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/34633\/revisions\/34636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media\/12676"}],"wp:attachment":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media?parent=34633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/categories?post=34633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/tags?post=34633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}