{"id":3565,"date":"2023-11-09T09:30:38","date_gmt":"2023-11-09T12:30:38","guid":{"rendered":"https:\/\/sulsc.com\/?p=3565"},"modified":"2023-11-09T09:17:22","modified_gmt":"2023-11-09T12:17:22","slug":"sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9","status":"publish","type":"post","link":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/","title":{"rendered":"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9)"},"content":{"rendered":"<p>A regi\u00e3o do Tai\u00f3, no bairro S\u00e3o Martinho, receber\u00e1 a pr\u00f3xima obra de rede de \u00e1gua no munic\u00edpio. A execu\u00e7\u00e3o consiste na melhoria da distribui\u00e7\u00e3o e velocidade da \u00e1gua, al\u00e9m da instala\u00e7\u00e3o de novo sistema de pressuriza\u00e7\u00e3o (booster). A obra, que era prevista para ocorrer em 2024, foi antecipada e acontecer\u00e1 a partir desta quinta-feira (9).<\/p>\n<p>Devido a sua localiza\u00e7\u00e3o geogr\u00e1fica, que faz com que o bairro esteja a quase oito quil\u00f4metros de dist\u00e2ncia do ponto de distribui\u00e7\u00e3o de \u00e1gua (ETA), e tamb\u00e9m por estar 47 metros acima da parte plana do munic\u00edpio, o S\u00e3o Martinho \u00e9 uma das regi\u00f5es mais complexas para a vaz\u00e3o de \u00e1gua em Tubar\u00e3o.<\/p>\n<p>Ap\u00f3s simula\u00e7\u00f5es hidr\u00e1ulicas da equipe da concession\u00e1ria, foi diagnosticado que havia a necessidade de refor\u00e7ar o sistema para substituir partes da rede antigas existentes e acrescentar novas redes e interliga\u00e7\u00f5es. E para que a \u00e1gua vencesse a diferen\u00e7a de n\u00edvel, tamb\u00e9m foi constatado a necessidade da instala\u00e7\u00e3o de mais um sistema de pressuriza\u00e7\u00e3o no bairro.<\/p>\n<p>Nos \u00faltimos anos a localidade ainda contou um crescimento exponencial de moradores, o que vem impactando na distribui\u00e7\u00e3o da \u00e1gua. \u201cQuanto mais alto, distante e com mais clientes utilizando, com menos press\u00e3o a \u00e1gua chega nos pontos de rede. Por isso, s\u00e3o implementados os boosters em pontos estrat\u00e9gicos a fim de manter a qualidade da \u00e1gua em todas as pontas de rede do munic\u00edpio\u201d, enfatiza o diretor da concession\u00e1ria, Marcelo Matos.<\/p>\n<p>Desta forma, a obra consiste em substituir 500 metros de rede antiga e incrementar 350 metros de nova, para atender todas as \u00e1reas. O projeto de instala\u00e7\u00e3o de um sistema de pressuriza\u00e7\u00e3o, que aconteceria em 2024, foi antecipado para ocorrer de maneira conjunta com essas necessidades. A execu\u00e7\u00e3o levar\u00e1 em torno de 30 dias para finaliza\u00e7\u00e3o.<\/p>\n<p>A Concession\u00e1ria investir\u00e1 cerca de R$ 390 mil nesta obra com o objetivo de levar benef\u00edcios para toda regi\u00e3o do Tai\u00f3, no bairro S\u00e3o Martinho. \u201cS\u00e3o mais de 500 pessoas que se beneficiar\u00e3o com a obra. \u00c9 uma das regi\u00f5es mais afastadas da cidade e estamos em constante evolu\u00e7\u00e3o para garantir os servi\u00e7os aos moradores de l\u00e1. Esperamos continuar abastecendo com qualidade os novos e antigos clientes, como j\u00e1 acontece nos outros bairros do munic\u00edpio\u201d, pontua o tamb\u00e9m diretor da Tubar\u00e3o Saneamento, Andr\u00e9 da Silva de Souza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A regi\u00e3o do Tai\u00f3, no bairro S\u00e3o Martinho, receber\u00e1 a pr\u00f3xima obra de rede de \u00e1gua no munic\u00edpio. A execu\u00e7\u00e3o consiste na melhoria da distribui\u00e7\u00e3o e velocidade da \u00e1gua, al\u00e9m da instala\u00e7\u00e3o de novo sistema de pressuriza\u00e7\u00e3o (booster). A obra, que era prevista para ocorrer em 2024, foi antecipada e acontecer\u00e1 a partir desta quinta-feira &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\"> <span class=\"screen-reader-text\">S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9)<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":3,"featured_media":3566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[1,21],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -\" \/>\n<meta property=\"og:description\" content=\"A regi\u00e3o do Tai\u00f3, no bairro S\u00e3o Martinho, receber\u00e1 a pr\u00f3xima obra de rede de \u00e1gua no munic\u00edpio. A execu\u00e7\u00e3o consiste na melhoria da distribui\u00e7\u00e3o e velocidade da \u00e1gua, al\u00e9m da instala\u00e7\u00e3o de novo sistema de pressuriza\u00e7\u00e3o (booster). A obra, que era prevista para ocorrer em 2024, foi antecipada e acontecer\u00e1 a partir desta quinta-feira &hellip; S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T12:30:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T12:17:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/Sao-Martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-Taio-a-partir-desta-quinta-feira-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/PortalSulSC\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Sul SC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\",\"url\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\",\"name\":\"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -\",\"isPartOf\":{\"@id\":\"https:\/\/sulsc.com\/#website\"},\"datePublished\":\"2023-11-09T12:30:38+00:00\",\"dateModified\":\"2023-11-09T12:17:22+00:00\",\"author\":{\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sulsc.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sulsc.com\/#website\",\"url\":\"https:\/\/sulsc.com\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sulsc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3\",\"name\":\"Reda\u00e7\u00e3o Sul SC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0\",\"url\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"contentUrl\":\"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png\",\"caption\":\"Reda\u00e7\u00e3o Sul SC\"},\"description\":\"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!\",\"sameAs\":[\"https:\/\/sulsc.com\/\",\"https:\/\/www.facebook.com\/profile.php?id=61559278119680\",\"https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC\",\"https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw\"],\"url\":\"https:\/\/sulsc.com\/index.php\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/","og_locale":"en_US","og_type":"article","og_title":"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -","og_description":"A regi\u00e3o do Tai\u00f3, no bairro S\u00e3o Martinho, receber\u00e1 a pr\u00f3xima obra de rede de \u00e1gua no munic\u00edpio. A execu\u00e7\u00e3o consiste na melhoria da distribui\u00e7\u00e3o e velocidade da \u00e1gua, al\u00e9m da instala\u00e7\u00e3o de novo sistema de pressuriza\u00e7\u00e3o (booster). A obra, que era prevista para ocorrer em 2024, foi antecipada e acontecer\u00e1 a partir desta quinta-feira &hellip; S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) Read More &raquo;","og_url":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/","article_author":"https:\/\/www.facebook.com\/profile.php?id=61559278119680","article_published_time":"2023-11-09T12:30:38+00:00","article_modified_time":"2023-11-09T12:17:22+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/11\/Sao-Martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-Taio-a-partir-desta-quinta-feira-9.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Sul SC","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/PortalSulSC","twitter_misc":{"Written by":"Reda\u00e7\u00e3o Sul SC","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/","url":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/","name":"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9) -","isPartOf":{"@id":"https:\/\/sulsc.com\/#website"},"datePublished":"2023-11-09T12:30:38+00:00","dateModified":"2023-11-09T12:17:22+00:00","author":{"@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3"},"breadcrumb":{"@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sulsc.com\/index.php\/2023\/11\/09\/sao-martinho-recebera-obras-na-rede-do-sistema-de-agua-e-novo-booster-taio-a-partir-desta-quinta-feira-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sulsc.com\/"},{"@type":"ListItem","position":2,"name":"S\u00e3o Martinho receber\u00e1 obras na rede do sistema de \u00e1gua e novo booster Tai\u00f3 a partir desta quinta-feira (9)"}]},{"@type":"WebSite","@id":"https:\/\/sulsc.com\/#website","url":"https:\/\/sulsc.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sulsc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sulsc.com\/#\/schema\/person\/84d2fc571684f6248ba83092f07750a3","name":"Reda\u00e7\u00e3o Sul SC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sulsc.com\/#\/schema\/person\/image\/e08d7fe2cc4ed596372063bbe852b8d0","url":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","contentUrl":"https:\/\/sulsc.com\/wp-content\/uploads\/2023\/09\/redacao.png","caption":"Reda\u00e7\u00e3o Sul SC"},"description":"Foco em um jornalismo imparcial, voltado \u00e0 qualidade dos seus conte\u00fados e, assim, levar informa\u00e7\u00e3o de valor que agregue \u00e0 vida dos leitores. Esta \u00e9 grande miss\u00e3o do Portal de Not\u00edcias Sul SC. N\u00e3o \u00e9 quantidade que muda o mundo, sempre foi e seguir\u00e1 sendo qualidade!","sameAs":["https:\/\/sulsc.com\/","https:\/\/www.facebook.com\/profile.php?id=61559278119680","https:\/\/www.instagram.com\/sulscportal\/?hl=pt-br","https:\/\/twitter.com\/https:\/\/twitter.com\/PortalSulSC","https:\/\/www.youtube.com\/channel\/UCv_BE8GeySluDov2n8qhVmw"],"url":"https:\/\/sulsc.com\/index.php\/author\/redacao\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3565"}],"collection":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/comments?post=3565"}],"version-history":[{"count":1,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3565\/revisions"}],"predecessor-version":[{"id":3567,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/posts\/3565\/revisions\/3567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media\/3566"}],"wp:attachment":[{"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/media?parent=3565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/categories?post=3565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sulsc.com\/index.php\/wp-json\/wp\/v2\/tags?post=3565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}